{"id":87071,"date":"2025-05-06T13:09:12","date_gmt":"2025-05-06T18:09:12","guid":{"rendered":"https:\/\/knightcenter.utexas.edu\/?p=87071"},"modified":"2025-05-06T13:09:12","modified_gmt":"2025-05-06T18:09:12","slug":"dale-vida-a-tus-historias-con-mapas-interactivos-sin-necesidad-de-programacion","status":"publish","type":"post","link":"https:\/\/knightcenter.utexas.edu\/es\/dale-vida-a-tus-historias-con-mapas-interactivos-sin-necesidad-de-programacion\/","title":{"rendered":"Dale vida a tus historias con mapas interactivos, \u00a1sin necesidad de programaci\u00f3n!"},"content":{"rendered":"<p dir=\"ltr\">Si alguna vez te has topado con un potente conjunto de datos y has pensado que podr\u00eda ser m\u00e1s impactante en forma de mapa, no eres el \u00fanico. Los mapas pueden revelar patrones, resaltar disparidades y ayudar al p\u00fablico a conectar con la informaci\u00f3n en formas que los simples n\u00fameros no pueden. Pero construir esos mapas desde cero a menudo parece fuera de nuestro alcance, especialmente sin experiencia en codificaci\u00f3n.<\/p>\n<p dir=\"ltr\">Ah\u00ed es donde entra en juego el nuevo curso avanzado de bajo costo del Centro Knight.<\/p>\n<p>Reg\u00edstrate en <a href=\"https:\/\/journalismcourses.org\/product\/hands-on-mapmaking-for-journalism-2025-edition\/\" target=\"_blank\" rel=\"noopener\"><em><strong>Elaboraci\u00f3n de mapas para periodismo \/ Edici\u00f3n 2025<\/strong><\/em><\/a>, un curso en l\u00ednea en ingl\u00e9s de cuatro semanas que se impartir\u00e1 del 2 al 29 de junio de 2025, donde aprender\u00e1s a convertir datos sin procesar en mapas interactivos y personalizables, sin necesidad de programaci\u00f3n. Utilizando herramientas gratuitas y de c\u00f3digo abierto como Protomaps y Datawrapper, desarrollar\u00e1s las habilidades necesarias para encontrar y preparar datos geogr\u00e1ficos, tomar decisiones de dise\u00f1o inteligentes y publicar mapas que tu audiencia pueda explorar.<\/p>\n<p><strong>\u00a1El registro ya est\u00e1 abierto por s\u00f3lo 95 d\u00f3lares. <a href=\"https:\/\/journalismcourses.org\/product\/hands-on-mapmaking-for-journalism-2025-edition\/\" target=\"_blank\" rel=\"noopener\">Reg\u00edstrate hoy mismo<\/a> e invierte en tus habilidades cartogr\u00e1ficas y narrativas! El curso se impartir\u00e1 del 2 al 29 de junio de 2025.<\/strong><\/p>\n<p><a href=\"https:\/\/journalismcourses.org\/product\/hands-on-mapmaking-for-journalism-2025-edition\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-85996 size-large\" src=\"https:\/\/knightcenter.utexas.edu\/wp-content\/uploads\/2025\/04\/ESP_BANNER-1-1024x386.png\" alt=\"Hands-on Mapmaking for Journalism\" width=\"1024\" height=\"386\" srcset=\"https:\/\/knightcenter.utexas.edu\/wp-content\/uploads\/2025\/04\/ESP_BANNER-1-1024x386.png 1024w, https:\/\/knightcenter.utexas.edu\/wp-content\/uploads\/2025\/04\/ESP_BANNER-1-300x113.png 300w, https:\/\/knightcenter.utexas.edu\/wp-content\/uploads\/2025\/04\/ESP_BANNER-1-768x289.png 768w, https:\/\/knightcenter.utexas.edu\/wp-content\/uploads\/2025\/04\/ESP_BANNER-1-1536x579.png 1536w, https:\/\/knightcenter.utexas.edu\/wp-content\/uploads\/2025\/04\/ESP_BANNER-1-2048x772.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/journalismcourses.org\/product\/hands-on-mapmaking-for-journalism-2025-edition\/\" target=\"_blank\" rel=\"noopener\"><em><strong>Elaboraci\u00f3n de mapas para periodismo \/ Edici\u00f3n 2025<\/strong><\/em><\/a> ser\u00e1 impartido en ingl\u00e9s por el experto en datos y cartograf\u00eda John Keefe, editor de datos meteorol\u00f3gicos en The New York Times, quien trabaja en historias visuales que ayudan a la audiencia a entender todo, desde huracanes hasta olas de calor. Su trabajo en The New York Times incluye la cobertura de las elecciones de 2020 y contribuciones a la cobertura que hizo el diario sobre la pandemia, la cual gan\u00f3 un Pulitzer. Keefe tambi\u00e9n ha dirigido equipos de datos y visuales en CNN, Quartz y WNYC, donde cre\u00f3 y dirigi\u00f3 el Data News Team.<\/p>\n<p>El material del curso est\u00e1 organizado en cinco m\u00f3dulos que abarcan diversos temas a trav\u00e9s de clases en video, lecturas y foros de debate:<\/p>\n<p><strong>M\u00f3dulo de introducci\u00f3n: Puesta en marcha con datos en clase, adem\u00e1s de gu\u00edas para encontrar los tuyos propios<\/strong><\/p>\n<p>Comenzaremos examinando el poder de los mapas en el periodismo a trav\u00e9s de ejemplos ic\u00f3nicos y proyectos del instructor, John Keefe. A continuaci\u00f3n, te proporcionaremos las herramientas y los datos que necesitar\u00e1s y te guiaremos para que elijas tu propio conjunto de datos con el que trabajar a lo largo del curso.<\/p>\n<ul>\n<li><strong>M\u00f3dulo 1: Creaci\u00f3n de mapas de datos con Datawrapper<\/strong><\/li>\n<\/ul>\n<p style=\"padding-left: 40px;\">Comienza a crear mapas vibrantes y listos para tus reportajes utilizando Datawrapper, una herramienta gratuita y f\u00e1cil de usar. Aprender\u00e1s a preparar tus datos, a asignar valores a \u00e1reas geogr\u00e1ficas y a crear mapas de coropletas pulidos para incluirlos en tus historias. Esta semana sienta las bases para todos tus proyectos cartogr\u00e1ficos.<\/p>\n<ul>\n<li><strong>M\u00f3dulo 2: Profundizaci\u00f3n en los principios de la cartograf\u00eda<\/strong><\/li>\n<\/ul>\n<p style=\"padding-left: 40px;\">Profundiza en los principios de la cartograf\u00eda y los datos geogr\u00e1ficos. Aprende a reconocer los distintos tipos de archivos, a utilizar herramientas gratuitas para explorarlos y convertirlos, y a entender c\u00f3mo funcionan los mapas en bloques o teselas. Tambi\u00e9n hablaremos de la \u00e9tica y la privacidad de los mapas, que son cuestiones clave cuando se trabaja con datos basados en ubicaci\u00f3n.<\/p>\n<ul>\n<li><strong>M\u00f3dulo 3: Creaci\u00f3n de mapas interactivos con Protomaps<\/strong><\/li>\n<\/ul>\n<p style=\"padding-left: 40px;\">Crea mapas interactivos y ampliables con Protomaps, una revolucionaria herramienta de c\u00f3digo abierto. Aprender\u00e1s a crear y dar estilo a tus bloques de mapas utilizando tus datos y a hacer que tus mapas sean responsivos y f\u00e1ciles de usar en dispositivos m\u00f3viles y de escritorio.<\/p>\n<ul>\n<li><strong>M\u00f3dulo 4: Alojar tus archivos Protomaps<\/strong><\/li>\n<\/ul>\n<p style=\"padding-left: 40px;\">Por \u00faltimo, te mostraremos c\u00f3mo publicar tus mapas en l\u00ednea. Aprende opciones de bajo costo para alojar tus archivos de mapas, desde el uso de los servidores de tu organizaci\u00f3n hasta la configuraci\u00f3n con AWS o el alojamiento gratuito de Protomaps. Cubriremos consejos para integrar tus mapas en tu CMS y presentarlos a tu audiencia.<\/p>\n<p>Una vez cumplidos con \u00e9xito los requisitos del curso, recibir\u00e1s un certificado de finalizaci\u00f3n, el cual reconocer\u00e1 tus nuevas habilidades en creaci\u00f3n de mapas para periodismo. Adem\u00e1s, habr\u00e1 sesiones en vivo en las que podr\u00e1s preguntar directamente a John Keefe sobre cualquier problema o reto que encuentres durante el curso. Para quienes no puedan asistir a las sesiones en vivo, \u00e9stas se grabar\u00e1n y se pondr\u00e1n a tu disposici\u00f3n para que las veas cuando te resulte m\u00e1s c\u00f3modo.<\/p>\n<p>Tanto si se trata de mapear tendencias electorales, infraestructuras locales, datos de salud p\u00fablica o patrones clim\u00e1ticos, este curso te proporcionar\u00e1 las herramientas necesarias para convertir r\u00e1pidamente cifras brutas en im\u00e1genes significativas.<\/p>\n<p>Reg\u00edstrate ahora y empieza a crear mapas, adem\u00e1s de informar, atraigan al p\u00fablico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ya est\u00e1 abierto el registro para un nuevo curso en ingl\u00e9s de bajo costo que te ense\u00f1ar\u00e1 a transformar datos en visualizaciones cartogr\u00e1ficas claras usando herramientas gratuitas como Datawrapper y Protomaps. Impartido por el experto John Keefe, se llevar\u00e1 a cabo del 2 al 29 de junio.<\/p>\n","protected":false},"author":9,"featured_media":87069,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[127],"tags":[],"class_list":["post-87071","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-journalism-courses-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.4 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Dale vida a tus historias con mapas interactivos, \u00a1sin necesidad de programaci\u00f3n! | Knight Center for Journalism in the Americas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/knightcenter.utexas.edu\/es\/dale-vida-a-tus-historias-con-mapas-interactivos-sin-necesidad-de-programacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dale vida a tus historias con mapas interactivos, \u00a1sin necesidad de programaci\u00f3n!\" \/>\n<meta property=\"og:description\" content=\"Ya est\u00e1 abierto el registro para un nuevo curso en ingl\u00e9s de bajo costo que te ense\u00f1ar\u00e1 a transformar datos en visualizaciones cartogr\u00e1ficas claras usando herramientas gratuitas como Datawrapper y Protomaps. Impartido por el experto John Keefe, se llevar\u00e1 a cabo del 2 al 29 de junio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/knightcenter.utexas.edu\/es\/dale-vida-a-tus-historias-con-mapas-interactivos-sin-necesidad-de-programacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Knight Center for Journalism in the Americas\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-06T18:09:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/knightcenter.utexas.edu\/wp-content\/uploads\/2025\/05\/ESP_MINI-BANNER.png\" \/>\n\t<meta property=\"og:image:width\" content=\"507\" \/>\n\t<meta property=\"og:image:height\" content=\"340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Filipa Rodrigues\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Filipa Rodrigues\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/es\\\/dale-vida-a-tus-historias-con-mapas-interactivos-sin-necesidad-de-programacion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/es\\\/dale-vida-a-tus-historias-con-mapas-interactivos-sin-necesidad-de-programacion\\\/\"},\"author\":{\"name\":\"Filipa Rodrigues\",\"@id\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/es\\\/#\\\/schema\\\/person\\\/4841f6fc828ff30af34979f573fb5ca8\"},\"headline\":\"Dale vida a tus historias con mapas interactivos, \u00a1sin necesidad de programaci\u00f3n!\",\"datePublished\":\"2025-05-06T18:09:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/es\\\/dale-vida-a-tus-historias-con-mapas-interactivos-sin-necesidad-de-programacion\\\/\"},\"wordCount\":839,\"image\":{\"@id\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/es\\\/dale-vida-a-tus-historias-con-mapas-interactivos-sin-necesidad-de-programacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/ESP_MINI-BANNER.png\",\"articleSection\":[\"Journalism Courses\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/es\\\/dale-vida-a-tus-historias-con-mapas-interactivos-sin-necesidad-de-programacion\\\/\",\"url\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/es\\\/dale-vida-a-tus-historias-con-mapas-interactivos-sin-necesidad-de-programacion\\\/\",\"name\":\"Dale vida a tus historias con mapas interactivos, \u00a1sin necesidad de programaci\u00f3n! | Knight Center for Journalism in the Americas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/es\\\/dale-vida-a-tus-historias-con-mapas-interactivos-sin-necesidad-de-programacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/es\\\/dale-vida-a-tus-historias-con-mapas-interactivos-sin-necesidad-de-programacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/ESP_MINI-BANNER.png\",\"datePublished\":\"2025-05-06T18:09:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/es\\\/#\\\/schema\\\/person\\\/4841f6fc828ff30af34979f573fb5ca8\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/es\\\/dale-vida-a-tus-historias-con-mapas-interactivos-sin-necesidad-de-programacion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/knightcenter.utexas.edu\\\/es\\\/dale-vida-a-tus-historias-con-mapas-interactivos-sin-necesidad-de-programacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/es\\\/dale-vida-a-tus-historias-con-mapas-interactivos-sin-necesidad-de-programacion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/ESP_MINI-BANNER.png\",\"contentUrl\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/ESP_MINI-BANNER.png\",\"width\":507,\"height\":340,\"caption\":\"Hands-on Mapmaking for Journalism\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/es\\\/dale-vida-a-tus-historias-con-mapas-interactivos-sin-necesidad-de-programacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dale vida a tus historias con mapas interactivos, \u00a1sin necesidad de programaci\u00f3n!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/es\\\/\",\"name\":\"Knight Center for Journalism in the Americas\",\"description\":\"Training, resources, and news for journalists\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/es\\\/#\\\/schema\\\/person\\\/4841f6fc828ff30af34979f573fb5ca8\",\"name\":\"Filipa Rodrigues\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/46a3352facba89c436eb45f3ad61e4a66c6a6273634b1cb43a1dfef6654eb01a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/46a3352facba89c436eb45f3ad61e4a66c6a6273634b1cb43a1dfef6654eb01a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/46a3352facba89c436eb45f3ad61e4a66c6a6273634b1cb43a1dfef6654eb01a?s=96&d=mm&r=g\",\"caption\":\"Filipa Rodrigues\"},\"url\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/es\\\/author\\\/filipa-rodrigues\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Dale vida a tus historias con mapas interactivos, \u00a1sin necesidad de programaci\u00f3n! | Knight Center for Journalism in the Americas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/knightcenter.utexas.edu\/es\/dale-vida-a-tus-historias-con-mapas-interactivos-sin-necesidad-de-programacion\/","og_locale":"es_ES","og_type":"article","og_title":"Dale vida a tus historias con mapas interactivos, \u00a1sin necesidad de programaci\u00f3n!","og_description":"Ya est\u00e1 abierto el registro para un nuevo curso en ingl\u00e9s de bajo costo que te ense\u00f1ar\u00e1 a transformar datos en visualizaciones cartogr\u00e1ficas claras usando herramientas gratuitas como Datawrapper y Protomaps. Impartido por el experto John Keefe, se llevar\u00e1 a cabo del 2 al 29 de junio.","og_url":"https:\/\/knightcenter.utexas.edu\/es\/dale-vida-a-tus-historias-con-mapas-interactivos-sin-necesidad-de-programacion\/","og_site_name":"Knight Center for Journalism in the Americas","article_published_time":"2025-05-06T18:09:12+00:00","og_image":[{"width":507,"height":340,"url":"https:\/\/knightcenter.utexas.edu\/wp-content\/uploads\/2025\/05\/ESP_MINI-BANNER.png","type":"image\/png"}],"author":"Filipa Rodrigues","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Filipa Rodrigues","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/knightcenter.utexas.edu\/es\/dale-vida-a-tus-historias-con-mapas-interactivos-sin-necesidad-de-programacion\/#article","isPartOf":{"@id":"https:\/\/knightcenter.utexas.edu\/es\/dale-vida-a-tus-historias-con-mapas-interactivos-sin-necesidad-de-programacion\/"},"author":{"name":"Filipa Rodrigues","@id":"https:\/\/knightcenter.utexas.edu\/es\/#\/schema\/person\/4841f6fc828ff30af34979f573fb5ca8"},"headline":"Dale vida a tus historias con mapas interactivos, \u00a1sin necesidad de programaci\u00f3n!","datePublished":"2025-05-06T18:09:12+00:00","mainEntityOfPage":{"@id":"https:\/\/knightcenter.utexas.edu\/es\/dale-vida-a-tus-historias-con-mapas-interactivos-sin-necesidad-de-programacion\/"},"wordCount":839,"image":{"@id":"https:\/\/knightcenter.utexas.edu\/es\/dale-vida-a-tus-historias-con-mapas-interactivos-sin-necesidad-de-programacion\/#primaryimage"},"thumbnailUrl":"https:\/\/knightcenter.utexas.edu\/wp-content\/uploads\/2025\/05\/ESP_MINI-BANNER.png","articleSection":["Journalism Courses"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/knightcenter.utexas.edu\/es\/dale-vida-a-tus-historias-con-mapas-interactivos-sin-necesidad-de-programacion\/","url":"https:\/\/knightcenter.utexas.edu\/es\/dale-vida-a-tus-historias-con-mapas-interactivos-sin-necesidad-de-programacion\/","name":"Dale vida a tus historias con mapas interactivos, \u00a1sin necesidad de programaci\u00f3n! | Knight Center for Journalism in the Americas","isPartOf":{"@id":"https:\/\/knightcenter.utexas.edu\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/knightcenter.utexas.edu\/es\/dale-vida-a-tus-historias-con-mapas-interactivos-sin-necesidad-de-programacion\/#primaryimage"},"image":{"@id":"https:\/\/knightcenter.utexas.edu\/es\/dale-vida-a-tus-historias-con-mapas-interactivos-sin-necesidad-de-programacion\/#primaryimage"},"thumbnailUrl":"https:\/\/knightcenter.utexas.edu\/wp-content\/uploads\/2025\/05\/ESP_MINI-BANNER.png","datePublished":"2025-05-06T18:09:12+00:00","author":{"@id":"https:\/\/knightcenter.utexas.edu\/es\/#\/schema\/person\/4841f6fc828ff30af34979f573fb5ca8"},"breadcrumb":{"@id":"https:\/\/knightcenter.utexas.edu\/es\/dale-vida-a-tus-historias-con-mapas-interactivos-sin-necesidad-de-programacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/knightcenter.utexas.edu\/es\/dale-vida-a-tus-historias-con-mapas-interactivos-sin-necesidad-de-programacion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/knightcenter.utexas.edu\/es\/dale-vida-a-tus-historias-con-mapas-interactivos-sin-necesidad-de-programacion\/#primaryimage","url":"https:\/\/knightcenter.utexas.edu\/wp-content\/uploads\/2025\/05\/ESP_MINI-BANNER.png","contentUrl":"https:\/\/knightcenter.utexas.edu\/wp-content\/uploads\/2025\/05\/ESP_MINI-BANNER.png","width":507,"height":340,"caption":"Hands-on Mapmaking for Journalism"},{"@type":"BreadcrumbList","@id":"https:\/\/knightcenter.utexas.edu\/es\/dale-vida-a-tus-historias-con-mapas-interactivos-sin-necesidad-de-programacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/knightcenter.utexas.edu\/es\/"},{"@type":"ListItem","position":2,"name":"Dale vida a tus historias con mapas interactivos, \u00a1sin necesidad de programaci\u00f3n!"}]},{"@type":"WebSite","@id":"https:\/\/knightcenter.utexas.edu\/es\/#website","url":"https:\/\/knightcenter.utexas.edu\/es\/","name":"Knight Center for Journalism in the Americas","description":"Training, resources, and news for journalists","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/knightcenter.utexas.edu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/knightcenter.utexas.edu\/es\/#\/schema\/person\/4841f6fc828ff30af34979f573fb5ca8","name":"Filipa Rodrigues","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/46a3352facba89c436eb45f3ad61e4a66c6a6273634b1cb43a1dfef6654eb01a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/46a3352facba89c436eb45f3ad61e4a66c6a6273634b1cb43a1dfef6654eb01a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/46a3352facba89c436eb45f3ad61e4a66c6a6273634b1cb43a1dfef6654eb01a?s=96&d=mm&r=g","caption":"Filipa Rodrigues"},"url":"https:\/\/knightcenter.utexas.edu\/es\/author\/filipa-rodrigues\/"}]}},"_links":{"self":[{"href":"https:\/\/knightcenter.utexas.edu\/es\/wp-json\/wp\/v2\/posts\/87071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/knightcenter.utexas.edu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/knightcenter.utexas.edu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/knightcenter.utexas.edu\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/knightcenter.utexas.edu\/es\/wp-json\/wp\/v2\/comments?post=87071"}],"version-history":[{"count":1,"href":"https:\/\/knightcenter.utexas.edu\/es\/wp-json\/wp\/v2\/posts\/87071\/revisions"}],"predecessor-version":[{"id":87072,"href":"https:\/\/knightcenter.utexas.edu\/es\/wp-json\/wp\/v2\/posts\/87071\/revisions\/87072"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/knightcenter.utexas.edu\/es\/wp-json\/wp\/v2\/media\/87069"}],"wp:attachment":[{"href":"https:\/\/knightcenter.utexas.edu\/es\/wp-json\/wp\/v2\/media?parent=87071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/knightcenter.utexas.edu\/es\/wp-json\/wp\/v2\/categories?post=87071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/knightcenter.utexas.edu\/es\/wp-json\/wp\/v2\/tags?post=87071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}