{"id":851,"date":"2020-04-04T16:47:15","date_gmt":"2020-04-04T21:47:15","guid":{"rendered":"https:\/\/live-knightcenter.pantheonsite.io\/?p=851"},"modified":"2020-06-05T13:40:56","modified_gmt":"2020-06-05T18:40:56","slug":"curso-sobre-a-liberdade-de-expressao-para-os-operadores-judiciais-no-meio-da-pandemia-tem-relevancia-importante","status":"publish","type":"post","link":"https:\/\/knightcenter.utexas.edu\/pt-br\/curso-sobre-a-liberdade-de-expressao-para-os-operadores-judiciais-no-meio-da-pandemia-tem-relevancia-importante\/","title":{"rendered":"Curso sobre a liberdade de express\u00e3o para os operadores judiciais no meio da pandemia tem 'relev\u00e2ncia importante'"},"content":{"rendered":"<p style=\"font-weight: 400;\">Em quase duas semanas, uma nova edi\u00e7\u00e3o do programa de treinamento em padr\u00f5es internacionais de liberdade de express\u00e3o destinada a ju\u00edzes, magistrados e outros operadores judiciais da Ibero-Am\u00e9rica, liderados pela UNESCO e pelo gabinete do Relator Especial para a Liberdade de Express\u00e3o da CIDH, em colabora\u00e7\u00e3o com o Centro Knight, iniciar\u00e1\u00a0aulas on-line.<\/p>\n<p style=\"font-weight: 400;\">O curso \"Marco Legal Internacional para liberdade de express\u00e3o, acesso \u00e0 informa\u00e7\u00e3o p\u00fablica e prote\u00e7\u00e3o de jornalistas\", que j\u00e1 atingiu quase 10.000 operadores judiciais na regi\u00e3o, coincide desta vez com a crise que o mundo enfrenta devido \u00e0 pandemia do COVID-19.\u00a0<b><strong><a style=\"font-weight: inherit; font-style: inherit;\" href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSc4gSFOr2Y0uM1Xugi0SumXcJkVU7r7JpC6WczX4J63Ua200Q\/viewform\">As inscri\u00e7\u00f5es ser\u00e3o encerradas em 5 de abril.<\/a><\/strong><\/b><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-846 alignleft\" src=\"https:\/\/live-knightcenter.pantheonsite.io\/wp-content\/uploads\/2020\/04\/corona2-300x196.png\" alt=\"Coronavirus\" width=\"400\" height=\"261\" srcset=\"https:\/\/knightcenter.utexas.edu\/wp-content\/uploads\/2020\/04\/corona2-300x196.png 300w, https:\/\/knightcenter.utexas.edu\/wp-content\/uploads\/2020\/04\/corona2.png 655w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: inherit; font-style: inherit;\">A pandemia n\u00e3o apenas nos for\u00e7ou a enfrentar desafios na \u00e1rea da sa\u00fade e da economia, mas tamb\u00e9m em como garantir os direitos humanos.<\/span><\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: inherit; font-style: inherit;\">\u201cEspecialmente em situa\u00e7\u00f5es de emerg\u00eancia, como a atual pandemia relacionada ao coronav\u00edrus, a tomada de decis\u00f5es pelos diferentes atores do Estado precisa passar por um processo de pesos e contrapesos para garantir que os direitos fundamentais continuem sendo protegidos com medidas emergenciais razo\u00e1veis \u200b\u200bque os governos precisam tomar, disse ao\u00a0<\/span><b><strong>Centro Knight\u00a0<\/strong><\/b>Guilherme Canela, chefe da Se\u00e7\u00e3o de Liberdade de Express\u00e3o e Seguran\u00e7a dos Jornalistas da UNESCO.<\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: inherit; font-style: inherit;\">\u201cNesse sentido, os operadores judiciais; particularmente ju\u00edzes, magistrados, e membros do Minist\u00e9rio P\u00fablico; eles devem estar vigilantes para que os padr\u00f5es internacionais relacionados a esses direitos fundamentais - e no caso de nosso\u00a0<\/span><a style=\"font-weight: inherit; font-style: inherit;\" href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSc4gSFOr2Y0uM1Xugi0SumXcJkVU7r7JpC6WczX4J63Ua200Q\/viewform\">curso<\/a>, relacionados \u00e0 liberdade de express\u00e3o, acesso \u00e0 informa\u00e7\u00e3o p\u00fablica e seguran\u00e7a dos jornalistas - sejam garantidos em rela\u00e7\u00e3o \u00e0s medidas que os governos est\u00e3o tomando para combater esta crise atual\u201d, acrescentou Canela, destacando a import\u00e2ncia desse tipo de treinamento.<\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: inherit; font-style: inherit;\">E o direito \u00e0 liberdade de express\u00e3o foi um dos mais violados em meio \u00e0s medidas tomadas para conter o v\u00edrus. \u00c9 uma situa\u00e7\u00e3o vivida desde que Li Wenliang, m\u00e9dico do hospital de Wuhan que alertou colegas em dezembro sobre um poss\u00edvel novo v\u00edrus,\u00a0<\/span><a style=\"font-weight: inherit; font-style: inherit;\" href=\"https:\/\/www.bbc.com\/mundo\/noticias-internacional-51371640\">foi acusado de \u201cfazer coment\u00e1rios falsos.<\/a>\u201d<\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: inherit; font-style: inherit;\">As a\u00e7\u00f5es na China,\u00a0<\/span><a style=\"font-weight: inherit; font-style: inherit;\" href=\"https:\/\/www.univision.com\/noticias\/opinion\/china-arresto-a-ocho-personas-por-desinformar-sobre-el-nuevo-virus-mortal-que-paso-con-ellas\">onde ainda n\u00e3o est\u00e3o claras as localiza\u00e7\u00f5es de pelo menos oito pessoas que foram detidas por relatar o COVID-19,\u00a0<\/a>n\u00e3o s\u00e3o as \u00fanicas. O Human Rights Watch chamou a aten\u00e7\u00e3o para governos como os de Bangladesh, Eti\u00f3pia, \u00cdndia e Birm\u00e2nia (Mianmar)<a style=\"font-weight: inherit; font-style: inherit;\" href=\"https:\/\/www.hrw.org\/es\/news\/2020\/03\/31\/en-la-lucha-contra-el-covid-19-los-bloqueos-de-internet-deben-terminar\">\u00a0por bloqueios na Internet<\/a>, ou Tail\u00e2ndia, que processou jornalistas por informar. Enquanto isso, o Rep\u00f3rteres Sem Fronteiras (RSF) e o Comit\u00ea para Prote\u00e7\u00e3o de Jornalistas (CPJ) rejeitaram as decis\u00f5es tomadas no Brasil, Honduras e Venezuela, onde pelo menos um jornalista\u00a0<a style=\"font-weight: inherit; font-style: inherit;\" href=\"https:\/\/knightcenter.utexas.edu\/blog\/00-21699-police-officers-arrest-venezuelan-journalist-who-reported-covid-19-situation-his-count\">foi preso<\/a>\u00a0por reportar o COVID-19.<\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: inherit; font-style: inherit;\">\u201cNesse sentido, temos certeza de que o curso tem uma tremenda relev\u00e2ncia, pois certamente haver\u00e1 d\u00favidas, haver\u00e1 \u00e1reas em que h\u00e1 ambiguidades e, no final das contas, a \u00faltima palavra ser\u00e1 para os poderes judiciais sobre quais medidas est\u00e3o em andamento de acordo com os padr\u00f5es internacionais e quais medidas n\u00e3o est\u00e3o de acordo com os padr\u00f5es internacionais\u201d, afirmou Canela.<\/span><\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: inherit; font-style: inherit;\">Preocupa\u00e7\u00f5es sobre a garantia de direitos fundamentais, como a liberdade de express\u00e3o, foram expressas por v\u00e1rias organiza\u00e7\u00f5es em todo o mundo. Em 19 de mar\u00e7o, os respons\u00e1veis pela \u00e1rea de liberdade de express\u00e3o e liberdade de m\u00eddia das Na\u00e7\u00f5es Unidas, a Comiss\u00e3o Interamericana de Direitos Humanos e o Representante para a Liberdade de M\u00eddia da Organiza\u00e7\u00e3o para Seguran\u00e7a e Coopera\u00e7\u00e3o na Europa emitiram um comunicado com recomenda\u00e7\u00f5es para evitar mais viola\u00e7\u00f5es.<\/span><\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: inherit; font-style: inherit;\">\"O direito de acesso \u00e0 informa\u00e7\u00e3o significa que os\u00a0<\/span><a style=\"font-weight: inherit; font-style: inherit;\" href=\"http:\/\/www.oas.org\/en\/iachr\/expression\/showarticle.asp?artID=1170&amp;lID=1\">governos devem estar fazendo esfor\u00e7os excepcionais para proteger o trabalho dos jornalistas<\/a>\", diz o comunicado. \u201cO jornalismo desempenha uma fun\u00e7\u00e3o crucial em um momento de emerg\u00eancia em sa\u00fade p\u00fablica, principalmente quando visa informar o p\u00fablico sobre informa\u00e7\u00f5es cr\u00edticas e monitorar as a\u00e7\u00f5es do governo. Instamos todos os governos a implementarem com robustez suas leis de liberdade de informa\u00e7\u00e3o para garantir que todos os indiv\u00edduos, especialmente jornalistas, tenham acesso \u00e0 informa\u00e7\u00e3o.\u201d<\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: inherit; font-style: inherit;\">Na declara\u00e7\u00e3o, os especialistas destacaram a obriga\u00e7\u00e3o do governo de fornecer informa\u00e7\u00f5es verdadeiras sobre a pandemia e garantir que ela atinja todas as pessoas, inclusive aquelas sem acesso \u00e0 Internet.<\/span><\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: inherit; font-style: inherit;\">Na Am\u00e9rica Latina, uma das restri\u00e7\u00f5es mais vis\u00edveis ocorreu na Venezuela, onde o\u00a0<\/span><a style=\"font-weight: inherit; font-style: inherit;\" href=\"https:\/\/knightcenter.utexas.edu\/blog\/00-21699-police-officers-arrest-venezuelan-journalist-who-reported-covid-19-situation-his-count\">jornalista Darvinson Rojas foi detido por agentes das For\u00e7as Especiais de A\u00e7\u00e3o<\/a>\u00a0(FAES) da Pol\u00edcia Nacional Bolivariana (PNB) em 21 de mar\u00e7o em Caracas. Jornalistas e a organiza\u00e7\u00e3o de defesa da liberdade de express\u00e3o do pa\u00eds apontaram isso como retalia\u00e7\u00e3o por sua cobertura do coronav\u00edrus na Venezuela. Em uma audi\u00eancia em 23 de mar\u00e7o, Rojas foi acusado de instigar \u00f3dio e instiga\u00e7\u00e3o p\u00fablica. Embora\u00a0<a style=\"font-weight: inherit; font-style: inherit;\" href=\"https:\/\/knightcenter.utexas.edu\/pt-br\/blog\/00-21721-jornalista-venezuelano-detido-depois-de-informar-sobre-pandemia-e-liberado-mas-process\">o jornalista tenha sido libertado em 2 de abril<\/a>, as acusa\u00e7\u00f5es pelas quais ele foi acusado n\u00e3o estavam claras.<\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: inherit; font-style: inherit;\">Tamb\u00e9m na Venezuela, a diretora do jornal La Verdad de Vargas,\u00a0<\/span><a style=\"font-weight: inherit; font-style: inherit;\" href=\"http:\/\/espaciopublico.ong\/fiscalia-interrogo-a-la-directora-de-la-verdad-de-vargas-por-informar-sobre-el-covid-19\/\">Beatriz Rodr\u00edguez, foi interrogada pelo Minist\u00e9rio P\u00fablico ap\u00f3s publicar informa\u00e7\u00f5es<\/a>\u00a0sobre um novo caso de coronav\u00edrus na regi\u00e3o.<\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: inherit; font-style: inherit;\">A RSF condenou a atitude do presidente do Brasil,\u00a0<\/span><a style=\"font-weight: inherit; font-style: inherit;\" href=\"https:\/\/rsf.org\/es\/noticias\/coronavirus-bolsonaro-se-encarniza-con-la-prensa-en-lugar-de-luchar-contra-la-pandemia\">Jair Bolsonaro, que \"multiplicou seus ataques p\u00fablicos contra a imprensa<\/a>, que ele considera respons\u00e1veis \u200b\u200bpor uma 'histeria' que visa gerar p\u00e2nico no pa\u00eds.\"<\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: inherit; font-style: inherit;\">\"Essa radicaliza\u00e7\u00e3o e intensifica\u00e7\u00e3o dos ataques contra a m\u00eddia s\u00e3o extremamente perturbadoras\", disse Emmanuel Colombi\u00e9, chefe do departamento da RSF na Am\u00e9rica Latina, segundo a organiza\u00e7\u00e3o. \u201cO presidente Bolsonaro est\u00e1 novamente mirando os mensageiros em vez do inimigo real e se torna cada vez mais irrespons\u00e1vel a cada dia. Durante esse per\u00edodo de pandemia, o governo brasileiro tem coisas mais importantes a fazer que perseguem a m\u00eddia, cuja reportagem agora \u00e9 mais essencial do que nunca.\u201d<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-852 alignright\" src=\"https:\/\/live-knightcenter.pantheonsite.io\/wp-content\/uploads\/2020\/04\/corona1-300x194.png\" alt=\"\" width=\"400\" height=\"258\" srcset=\"https:\/\/knightcenter.utexas.edu\/wp-content\/uploads\/2020\/04\/corona1-300x194.png 300w, https:\/\/knightcenter.utexas.edu\/wp-content\/uploads\/2020\/04\/corona1.png 741w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: inherit; font-style: inherit;\">O CPJ tamb\u00e9m condenou o Brasil, desta vez pela decis\u00e3o de\u00a0<\/span><a style=\"font-weight: inherit; font-style: inherit;\" href=\"https:\/\/cpj.org\/2020\/03\/brazil-restricts-access-to-government-information-.php\">suspender provisoriamente os prazos para as autoridades responderem\u00a0solicita\u00e7\u00f5es de informa\u00e7\u00f5es<\/a>\u00a0e proibi\u00e7\u00e3o de apela\u00e7\u00f5es caso sejam negadas. A a\u00e7\u00e3o, segundo o CPJ, ocorrer\u00e1 durante o per\u00edodo de \"estado de calamidade\" devido ao COVID-19.<\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: inherit; font-style: inherit;\">\"Em meio a uma crescente crise de sa\u00fade p\u00fablica, \u00e9 mais vital para cidad\u00e3os brasileiros terem acesso a informa\u00e7\u00f5es confi\u00e1veis \u200b\", disse Natalie Southwick, coordenadora do programa na Am\u00e9rica Central e do Sul. \"O Congresso deve rejeitar esta tentativa de usar medidas de emerg\u00eancia como uma desculpa para reprimir a liberdade de express\u00e3o ou reverter a situa\u00e7\u00e3o, constitucionalmente garantido o acesso \u00e0 informa\u00e7\u00e3o\".<\/span><\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: inherit; font-style: inherit;\">O ombudsman de Direitos Humanos de El Salvador denunciou que\u00a0<\/span><a style=\"font-weight: inherit; font-style: inherit;\" href=\"https:\/\/www.dw.com\/es\/el-salvador-denuncian-restricciones-a-la-prensa-durante-emergencia-por-coronavirus\/a-53001593\">a imprensa enfrentou uma s\u00e9rie de restri\u00e7\u00f5es ao trabalho da Pol\u00edcia Nacional Civil e das For\u00e7as Armadas<\/a>\u00a0em meio \u00e0 quarentena tomada para lidar com a crise, informou a DW. Houve at\u00e9 a destrui\u00e7\u00e3o de material jornal\u00edstico, acrescentou o site.<\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: inherit; font-style: inherit;\">Por decreto do presidente de Honduras, Juan Orlando Hern\u00e1ndez, foi estabelecido um estado de emerg\u00eancia que suspendeu alguns artigos da Constitui\u00e7\u00e3o por sete dias,\u00a0<\/span><a style=\"font-weight: inherit; font-style: inherit;\" href=\"https:\/\/cpj.org\/2020\/03\/honduran-government-declares-state-of-emergency-su.php\">incluindo o que garante liberdade de express\u00e3o sem censura<\/a>.<\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: inherit; font-style: inherit;\">Na Rep\u00fablica Dominicana, onde um toque de recolher foi decretado,\u00a0<\/span><a style=\"font-weight: inherit; font-style: inherit;\" href=\"http:\/\/www.fundamedios.us\/incidentes\/republicadominicana-periodista-detencion-covid19\/\">alguns jornalistas foram detidos por viol\u00e1-lo,<\/a>\u00a0apesar do decreto isentar os jornalistas de cumprirem, dada a natureza de seu trabalho.<\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: inherit; font-style: inherit;\">\u201cSegundo a lei internacional de direitos humanos, os governos t\u00eam a obriga\u00e7\u00e3o de proteger o direito \u00e0 liberdade de express\u00e3o, incluindo o direito de buscar, receber e transmitir informa\u00e7\u00f5es de todos os tipos, independentemente de fronteiras\u201d, disse a Human Rights Watch. \"<\/span><a style=\"font-weight: inherit; font-style: inherit;\" href=\"https:\/\/www.hrw.org\/news\/2020\/03\/19\/human-rights-dimensions-covid-19-response\">Restri\u00e7\u00f5es permitidas \u00e0 liberdade de express\u00e3o por raz\u00f5es de sa\u00fade p\u00fablica<\/a>, mencionadas acima, n\u00e3o podem p\u00f4r em risco o pr\u00f3prio direito\".<\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: inherit; font-style: inherit;\">A\u00a0<\/span><a style=\"font-weight: inherit; font-style: inherit;\" href=\"https:\/\/www.indexoncensorship.org\/disease-control\/\">campanha Index on Censorship criou um mapa interativo onde viola\u00e7\u00f5es desse direito podem ser vistas em todo o mundo<\/a>. Tamb\u00e9m \u00e9 poss\u00edvel relatar casos.<\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: inherit; font-style: inherit;\">Para ajudar a garantir o trabalho dos jornalistas e outras medidas que a m\u00eddia deve adotar para cobrir a pandemia, o\u00a0<\/span><a style=\"font-weight: inherit; font-style: inherit;\" href=\"https:\/\/cpj.org\/covid-19\/\">CPJ possui uma se\u00e7\u00e3o espec\u00edfica sobre esse assunto<\/a>.<\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: inherit; font-style: inherit;\">Al\u00e9m disso, em 1\u00ba de abril, o\u00a0<\/span><a style=\"font-weight: inherit; font-style: inherit;\" href=\"https:\/\/cpj.org\/blog\/2020\/04\/cpj-partners-call-on-council-of-europe-to-protect-.php\">CPJ anunciou uma alian\u00e7a com o Conselho da Europa para proteger a liberdade de imprensa em\u00a0<\/a>meio \u00e0 pandemia do COVID-19.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em quase duas semanas, uma nova edi\u00e7\u00e3o do programa de treinamento em padr\u00f5es internacionais de liberdade de express\u00e3o destinada a ju\u00edzes, magistrados e outros operadores judiciais da Ibero-Am\u00e9rica, liderados pela UNESCO e pelo gabinete do Relator Especial para a Liberdade de Express\u00e3o da CIDH, em colabora\u00e7\u00e3o com o Centro Knight, iniciar\u00e1\u00a0aulas on-line. O curso \"Marco [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":846,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[126],"tags":[144],"class_list":["post-851","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-journalism-courses-pt-br","tag-liberdade-de-expressao-pt-br"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.4 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Curso sobre a liberdade de express\u00e3o para os operadores judiciais no meio da pandemia tem &#039;relev\u00e2ncia importante&#039; | Knight Center for Journalism in the Americas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/knightcenter.utexas.edu\/pt-br\/curso-sobre-a-liberdade-de-expressao-para-os-operadores-judiciais-no-meio-da-pandemia-tem-relevancia-importante\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Curso sobre a liberdade de express\u00e3o para os operadores judiciais no meio da pandemia tem &#039;relev\u00e2ncia importante&#039;\" \/>\n<meta property=\"og:description\" content=\"Em quase duas semanas, uma nova edi\u00e7\u00e3o do programa de treinamento em padr\u00f5es internacionais de liberdade de express\u00e3o destinada a ju\u00edzes, magistrados e outros operadores judiciais da Ibero-Am\u00e9rica, liderados pela UNESCO e pelo gabinete do Relator Especial para a Liberdade de Express\u00e3o da CIDH, em colabora\u00e7\u00e3o com o Centro Knight, iniciar\u00e1\u00a0aulas on-line. O curso &quot;Marco [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/knightcenter.utexas.edu\/pt-br\/curso-sobre-a-liberdade-de-expressao-para-os-operadores-judiciais-no-meio-da-pandemia-tem-relevancia-importante\/\" \/>\n<meta property=\"og:site_name\" content=\"Knight Center for Journalism in the Americas\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-04T21:47:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-05T18:40:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/knightcenter.utexas.edu\/wp-content\/uploads\/2020\/04\/corona2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"655\" \/>\n\t<meta property=\"og:image:height\" content=\"427\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Teresa Mioli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Teresa Mioli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/pt-br\\\/curso-sobre-a-liberdade-de-expressao-para-os-operadores-judiciais-no-meio-da-pandemia-tem-relevancia-importante\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/pt-br\\\/curso-sobre-a-liberdade-de-expressao-para-os-operadores-judiciais-no-meio-da-pandemia-tem-relevancia-importante\\\/\"},\"author\":{\"name\":\"Teresa Mioli\",\"@id\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/pt-br\\\/#\\\/schema\\\/person\\\/0ae5abed263deaf3b5268d451371b58a\"},\"headline\":\"Curso sobre a liberdade de express\u00e3o para os operadores judiciais no meio da pandemia tem 'relev\u00e2ncia importante'\",\"datePublished\":\"2020-04-04T21:47:15+00:00\",\"dateModified\":\"2020-06-05T18:40:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/pt-br\\\/curso-sobre-a-liberdade-de-expressao-para-os-operadores-judiciais-no-meio-da-pandemia-tem-relevancia-importante\\\/\"},\"wordCount\":1424,\"image\":{\"@id\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/pt-br\\\/curso-sobre-a-liberdade-de-expressao-para-os-operadores-judiciais-no-meio-da-pandemia-tem-relevancia-importante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/corona2.png\",\"keywords\":[\"Liberdade de Express\u00e3o\"],\"articleSection\":[\"Journalism Courses\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/pt-br\\\/curso-sobre-a-liberdade-de-expressao-para-os-operadores-judiciais-no-meio-da-pandemia-tem-relevancia-importante\\\/\",\"url\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/pt-br\\\/curso-sobre-a-liberdade-de-expressao-para-os-operadores-judiciais-no-meio-da-pandemia-tem-relevancia-importante\\\/\",\"name\":\"Curso sobre a liberdade de express\u00e3o para os operadores judiciais no meio da pandemia tem 'relev\u00e2ncia importante' | Knight Center for Journalism in the Americas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/pt-br\\\/curso-sobre-a-liberdade-de-expressao-para-os-operadores-judiciais-no-meio-da-pandemia-tem-relevancia-importante\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/pt-br\\\/curso-sobre-a-liberdade-de-expressao-para-os-operadores-judiciais-no-meio-da-pandemia-tem-relevancia-importante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/corona2.png\",\"datePublished\":\"2020-04-04T21:47:15+00:00\",\"dateModified\":\"2020-06-05T18:40:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/pt-br\\\/#\\\/schema\\\/person\\\/0ae5abed263deaf3b5268d451371b58a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/pt-br\\\/curso-sobre-a-liberdade-de-expressao-para-os-operadores-judiciais-no-meio-da-pandemia-tem-relevancia-importante\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/knightcenter.utexas.edu\\\/pt-br\\\/curso-sobre-a-liberdade-de-expressao-para-os-operadores-judiciais-no-meio-da-pandemia-tem-relevancia-importante\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/pt-br\\\/curso-sobre-a-liberdade-de-expressao-para-os-operadores-judiciais-no-meio-da-pandemia-tem-relevancia-importante\\\/#primaryimage\",\"url\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/corona2.png\",\"contentUrl\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/corona2.png\",\"width\":655,\"height\":427,\"caption\":\"Coronavirus\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/pt-br\\\/curso-sobre-a-liberdade-de-expressao-para-os-operadores-judiciais-no-meio-da-pandemia-tem-relevancia-importante\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Curso sobre a liberdade de express\u00e3o para os operadores judiciais no meio da pandemia tem 'relev\u00e2ncia importante'\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/pt-br\\\/\",\"name\":\"Knight Center for Journalism in the Americas\",\"description\":\"Training, resources, and news for journalists\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/pt-br\\\/#\\\/schema\\\/person\\\/0ae5abed263deaf3b5268d451371b58a\",\"name\":\"Teresa Mioli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4d0ceaf097850db8652c68bcc255f4c7017a16afefc82235359b7d25de801c1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4d0ceaf097850db8652c68bcc255f4c7017a16afefc82235359b7d25de801c1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4d0ceaf097850db8652c68bcc255f4c7017a16afefc82235359b7d25de801c1?s=96&d=mm&r=g\",\"caption\":\"Teresa Mioli\"},\"description\":\"Teresa Mioli is the editorial manager for the Knight Center for Journalism in the Americas. She is interested in press freedom, democratization, and investigative journalism in Latin America and is dedicated to increasing awareness about the importance of independent news media to the health of democracies. She produces journalistic work with the aim of helping people to make informed decisions about their lives and societies and wants to make sure other journalists are able to do the same. She has Bachelors' degrees in Journalism and Plan II Honors (Liberal Arts) and a Master's degree in Latin American Studies, all from the University of Texas at Austin. She started her journalistic career at The Beaumont Enterprise in Southeast Texas where she last worked as a breaking news reporter. Teresa Mioli es la gerente editorial del Centro Knight para el Periodismo en las Am\u00e9ricas. Es una periodista con inter\u00e9s en la libertad de prensa, la democratizaci\u00f3n y el periodismo investigativo en Am\u00e9rica Latina y est\u00e1 dedicada a crear mayor consciencia sobre la importancia de los medios noticiosos independientes para la salud de las democracias. El objetivo de su trabajo period\u00edstico es ayudar las personas para que tomen decisiones informadas sobre sus vidas y sus sociedades, y busca que otros periodistas tengan la posibilidad de hacer lo mismo. Teresa tiene una licenciatura en Periodismo y Artes liberales (Plan II Honors), y una maestr\u00eda en Estudios Latinoamericanos, todos de la Universidad de Texas en Austin. Empez\u00f3 su carrera en periodismo en The Beaumont Enterprise al sureste de Texas, en donde recientemente trabaj\u00f3 como reportera de noticias de \u00faltima hora. Anteriormente ella fue la editora de LatAm Journalism Review del Centro Knight. Teresa Mioli \u00e9 gerente editorial do Centro Knight para o Jornalismo nas Am\u00e9ricas. Ela se interessa por liberdade de imprensa, democratiza\u00e7\u00e3o e jornalismo investigativo na Am\u00e9rica Latina e se dedica a aumentar a conscientiza\u00e7\u00e3o sobre a import\u00e2ncia da m\u00eddia independente para a sa\u00fade das democracias. Ela produz trabalhos jornal\u00edsticos com o objetivo de ajudar as pessoas a tomarem decis\u00f5es informadas sobre suas vidas e sociedades e deseja garantir que outros jornalistas possam fazer o mesmo. Ela tem bacharelado em jornalismo e artes liberais e um mestrado em Estudos Latino-Americanos, todos pela Universidade do Texas em Austin. Ela come\u00e7ou sua carreira jornal\u00edstica na The Beaumont Enterprise no sudeste do Texas, onde trabalhou pela \u00faltima vez como rep\u00f3rter de not\u00edcias de \u00faltima hora.\",\"url\":\"https:\\\/\\\/knightcenter.utexas.edu\\\/pt-br\\\/author\\\/teresa-mioli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Curso sobre a liberdade de express\u00e3o para os operadores judiciais no meio da pandemia tem 'relev\u00e2ncia importante' | Knight Center for Journalism in the Americas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/knightcenter.utexas.edu\/pt-br\/curso-sobre-a-liberdade-de-expressao-para-os-operadores-judiciais-no-meio-da-pandemia-tem-relevancia-importante\/","og_locale":"pt_BR","og_type":"article","og_title":"Curso sobre a liberdade de express\u00e3o para os operadores judiciais no meio da pandemia tem 'relev\u00e2ncia importante'","og_description":"Em quase duas semanas, uma nova edi\u00e7\u00e3o do programa de treinamento em padr\u00f5es internacionais de liberdade de express\u00e3o destinada a ju\u00edzes, magistrados e outros operadores judiciais da Ibero-Am\u00e9rica, liderados pela UNESCO e pelo gabinete do Relator Especial para a Liberdade de Express\u00e3o da CIDH, em colabora\u00e7\u00e3o com o Centro Knight, iniciar\u00e1\u00a0aulas on-line. O curso \"Marco [&hellip;]","og_url":"https:\/\/knightcenter.utexas.edu\/pt-br\/curso-sobre-a-liberdade-de-expressao-para-os-operadores-judiciais-no-meio-da-pandemia-tem-relevancia-importante\/","og_site_name":"Knight Center for Journalism in the Americas","article_published_time":"2020-04-04T21:47:15+00:00","article_modified_time":"2020-06-05T18:40:56+00:00","og_image":[{"width":655,"height":427,"url":"https:\/\/knightcenter.utexas.edu\/wp-content\/uploads\/2020\/04\/corona2.png","type":"image\/png"}],"author":"Teresa Mioli","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Teresa Mioli","Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/knightcenter.utexas.edu\/pt-br\/curso-sobre-a-liberdade-de-expressao-para-os-operadores-judiciais-no-meio-da-pandemia-tem-relevancia-importante\/#article","isPartOf":{"@id":"https:\/\/knightcenter.utexas.edu\/pt-br\/curso-sobre-a-liberdade-de-expressao-para-os-operadores-judiciais-no-meio-da-pandemia-tem-relevancia-importante\/"},"author":{"name":"Teresa Mioli","@id":"https:\/\/knightcenter.utexas.edu\/pt-br\/#\/schema\/person\/0ae5abed263deaf3b5268d451371b58a"},"headline":"Curso sobre a liberdade de express\u00e3o para os operadores judiciais no meio da pandemia tem 'relev\u00e2ncia importante'","datePublished":"2020-04-04T21:47:15+00:00","dateModified":"2020-06-05T18:40:56+00:00","mainEntityOfPage":{"@id":"https:\/\/knightcenter.utexas.edu\/pt-br\/curso-sobre-a-liberdade-de-expressao-para-os-operadores-judiciais-no-meio-da-pandemia-tem-relevancia-importante\/"},"wordCount":1424,"image":{"@id":"https:\/\/knightcenter.utexas.edu\/pt-br\/curso-sobre-a-liberdade-de-expressao-para-os-operadores-judiciais-no-meio-da-pandemia-tem-relevancia-importante\/#primaryimage"},"thumbnailUrl":"https:\/\/knightcenter.utexas.edu\/wp-content\/uploads\/2020\/04\/corona2.png","keywords":["Liberdade de Express\u00e3o"],"articleSection":["Journalism Courses"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/knightcenter.utexas.edu\/pt-br\/curso-sobre-a-liberdade-de-expressao-para-os-operadores-judiciais-no-meio-da-pandemia-tem-relevancia-importante\/","url":"https:\/\/knightcenter.utexas.edu\/pt-br\/curso-sobre-a-liberdade-de-expressao-para-os-operadores-judiciais-no-meio-da-pandemia-tem-relevancia-importante\/","name":"Curso sobre a liberdade de express\u00e3o para os operadores judiciais no meio da pandemia tem 'relev\u00e2ncia importante' | Knight Center for Journalism in the Americas","isPartOf":{"@id":"https:\/\/knightcenter.utexas.edu\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/knightcenter.utexas.edu\/pt-br\/curso-sobre-a-liberdade-de-expressao-para-os-operadores-judiciais-no-meio-da-pandemia-tem-relevancia-importante\/#primaryimage"},"image":{"@id":"https:\/\/knightcenter.utexas.edu\/pt-br\/curso-sobre-a-liberdade-de-expressao-para-os-operadores-judiciais-no-meio-da-pandemia-tem-relevancia-importante\/#primaryimage"},"thumbnailUrl":"https:\/\/knightcenter.utexas.edu\/wp-content\/uploads\/2020\/04\/corona2.png","datePublished":"2020-04-04T21:47:15+00:00","dateModified":"2020-06-05T18:40:56+00:00","author":{"@id":"https:\/\/knightcenter.utexas.edu\/pt-br\/#\/schema\/person\/0ae5abed263deaf3b5268d451371b58a"},"breadcrumb":{"@id":"https:\/\/knightcenter.utexas.edu\/pt-br\/curso-sobre-a-liberdade-de-expressao-para-os-operadores-judiciais-no-meio-da-pandemia-tem-relevancia-importante\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/knightcenter.utexas.edu\/pt-br\/curso-sobre-a-liberdade-de-expressao-para-os-operadores-judiciais-no-meio-da-pandemia-tem-relevancia-importante\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/knightcenter.utexas.edu\/pt-br\/curso-sobre-a-liberdade-de-expressao-para-os-operadores-judiciais-no-meio-da-pandemia-tem-relevancia-importante\/#primaryimage","url":"https:\/\/knightcenter.utexas.edu\/wp-content\/uploads\/2020\/04\/corona2.png","contentUrl":"https:\/\/knightcenter.utexas.edu\/wp-content\/uploads\/2020\/04\/corona2.png","width":655,"height":427,"caption":"Coronavirus"},{"@type":"BreadcrumbList","@id":"https:\/\/knightcenter.utexas.edu\/pt-br\/curso-sobre-a-liberdade-de-expressao-para-os-operadores-judiciais-no-meio-da-pandemia-tem-relevancia-importante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/knightcenter.utexas.edu\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Curso sobre a liberdade de express\u00e3o para os operadores judiciais no meio da pandemia tem 'relev\u00e2ncia importante'"}]},{"@type":"WebSite","@id":"https:\/\/knightcenter.utexas.edu\/pt-br\/#website","url":"https:\/\/knightcenter.utexas.edu\/pt-br\/","name":"Knight Center for Journalism in the Americas","description":"Training, resources, and news for journalists","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/knightcenter.utexas.edu\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/knightcenter.utexas.edu\/pt-br\/#\/schema\/person\/0ae5abed263deaf3b5268d451371b58a","name":"Teresa Mioli","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/f4d0ceaf097850db8652c68bcc255f4c7017a16afefc82235359b7d25de801c1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f4d0ceaf097850db8652c68bcc255f4c7017a16afefc82235359b7d25de801c1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f4d0ceaf097850db8652c68bcc255f4c7017a16afefc82235359b7d25de801c1?s=96&d=mm&r=g","caption":"Teresa Mioli"},"description":"Teresa Mioli is the editorial manager for the Knight Center for Journalism in the Americas. She is interested in press freedom, democratization, and investigative journalism in Latin America and is dedicated to increasing awareness about the importance of independent news media to the health of democracies. She produces journalistic work with the aim of helping people to make informed decisions about their lives and societies and wants to make sure other journalists are able to do the same. She has Bachelors' degrees in Journalism and Plan II Honors (Liberal Arts) and a Master's degree in Latin American Studies, all from the University of Texas at Austin. She started her journalistic career at The Beaumont Enterprise in Southeast Texas where she last worked as a breaking news reporter. Teresa Mioli es la gerente editorial del Centro Knight para el Periodismo en las Am\u00e9ricas. Es una periodista con inter\u00e9s en la libertad de prensa, la democratizaci\u00f3n y el periodismo investigativo en Am\u00e9rica Latina y est\u00e1 dedicada a crear mayor consciencia sobre la importancia de los medios noticiosos independientes para la salud de las democracias. El objetivo de su trabajo period\u00edstico es ayudar las personas para que tomen decisiones informadas sobre sus vidas y sus sociedades, y busca que otros periodistas tengan la posibilidad de hacer lo mismo. Teresa tiene una licenciatura en Periodismo y Artes liberales (Plan II Honors), y una maestr\u00eda en Estudios Latinoamericanos, todos de la Universidad de Texas en Austin. Empez\u00f3 su carrera en periodismo en The Beaumont Enterprise al sureste de Texas, en donde recientemente trabaj\u00f3 como reportera de noticias de \u00faltima hora. Anteriormente ella fue la editora de LatAm Journalism Review del Centro Knight. Teresa Mioli \u00e9 gerente editorial do Centro Knight para o Jornalismo nas Am\u00e9ricas. Ela se interessa por liberdade de imprensa, democratiza\u00e7\u00e3o e jornalismo investigativo na Am\u00e9rica Latina e se dedica a aumentar a conscientiza\u00e7\u00e3o sobre a import\u00e2ncia da m\u00eddia independente para a sa\u00fade das democracias. Ela produz trabalhos jornal\u00edsticos com o objetivo de ajudar as pessoas a tomarem decis\u00f5es informadas sobre suas vidas e sociedades e deseja garantir que outros jornalistas possam fazer o mesmo. Ela tem bacharelado em jornalismo e artes liberais e um mestrado em Estudos Latino-Americanos, todos pela Universidade do Texas em Austin. Ela come\u00e7ou sua carreira jornal\u00edstica na The Beaumont Enterprise no sudeste do Texas, onde trabalhou pela \u00faltima vez como rep\u00f3rter de not\u00edcias de \u00faltima hora.","url":"https:\/\/knightcenter.utexas.edu\/pt-br\/author\/teresa-mioli\/"}]}},"_links":{"self":[{"href":"https:\/\/knightcenter.utexas.edu\/pt-br\/wp-json\/wp\/v2\/posts\/851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/knightcenter.utexas.edu\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/knightcenter.utexas.edu\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/knightcenter.utexas.edu\/pt-br\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/knightcenter.utexas.edu\/pt-br\/wp-json\/wp\/v2\/comments?post=851"}],"version-history":[{"count":1,"href":"https:\/\/knightcenter.utexas.edu\/pt-br\/wp-json\/wp\/v2\/posts\/851\/revisions"}],"predecessor-version":[{"id":855,"href":"https:\/\/knightcenter.utexas.edu\/pt-br\/wp-json\/wp\/v2\/posts\/851\/revisions\/855"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/knightcenter.utexas.edu\/pt-br\/wp-json\/wp\/v2\/media\/846"}],"wp:attachment":[{"href":"https:\/\/knightcenter.utexas.edu\/pt-br\/wp-json\/wp\/v2\/media?parent=851"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/knightcenter.utexas.edu\/pt-br\/wp-json\/wp\/v2\/categories?post=851"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/knightcenter.utexas.edu\/pt-br\/wp-json\/wp\/v2\/tags?post=851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}